{"id":194,"date":"2024-12-16T22:09:05","date_gmt":"2024-12-16T22:09:05","guid":{"rendered":"https:\/\/geneva-residence-paprika.ms2.decms.eu\/services-equipements\/"},"modified":"2025-07-10T15:10:56","modified_gmt":"2025-07-10T15:10:56","slug":"servizi-e-attrezzature","status":"publish","type":"page","link":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/","title":{"rendered":"Servizi e Attrezzature"},"content":{"rendered":"<p style=\"text-align: center;\">Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa.<\/p>\n<p style=\"text-align: center;\">Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l&#8217;accesso Wi-Fi.<\/p>\n<p style=\"text-align: center;\">\u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) all&#8217;arrivo, in base alla disponibilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l&#8217;accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) [&hellip;]<\/p>\n","protected":false},"author":192,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-services.php","meta":{"footnotes":""},"class_list":["post-194","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizi e Attrezzature - Geneva Residence -<\/title>\n<meta name=\"description\" content=\"Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l&#039;accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) all&#039;arrivo, in base alla disponibilit\u00e0. &nbsp;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizi e Attrezzature - Geneva Residence -\" \/>\n<meta property=\"og:description\" content=\"Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l&#039;accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) all&#039;arrivo, in base alla disponibilit\u00e0. &nbsp;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/\" \/>\n<meta property=\"og:site_name\" content=\"Geneva Residence\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T15:10:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/servizi-e-attrezzature\\\/\",\"url\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/servizi-e-attrezzature\\\/\",\"name\":\"Servizi e Attrezzature - Geneva Residence -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/#website\"},\"datePublished\":\"2024-12-16T22:09:05+00:00\",\"dateModified\":\"2025-07-10T15:10:56+00:00\",\"description\":\"Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l'accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\\\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\\\/notte) all'arrivo, in base alla disponibilit\u00e0. &nbsp;.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/servizi-e-attrezzature\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/servizi-e-attrezzature\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/servizi-e-attrezzature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi e Attrezzature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/\",\"name\":\"Geneva Residence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/#organization\",\"name\":\"Geneva Residence\",\"url\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/geneva-residence-paprika.ms2.decms.eu\\\/wp-content\\\/uploads\\\/sites\\\/183\\\/2024\\\/12\\\/Logo-pour-en-tete-1.png\",\"contentUrl\":\"https:\\\/\\\/geneva-residence-paprika.ms2.decms.eu\\\/wp-content\\\/uploads\\\/sites\\\/183\\\/2024\\\/12\\\/Logo-pour-en-tete-1.png\",\"width\":2200,\"height\":795,\"caption\":\"Geneva Residence\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geneva-residence.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizi e Attrezzature - Geneva Residence -","description":"Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l'accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) all'arrivo, in base alla disponibilit\u00e0. &nbsp;.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/","og_locale":"it_IT","og_type":"article","og_title":"Servizi e Attrezzature - Geneva Residence -","og_description":"Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l'accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) all'arrivo, in base alla disponibilit\u00e0. &nbsp;.","og_url":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/","og_site_name":"Geneva Residence","article_modified_time":"2025-07-10T15:10:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/","url":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/","name":"Servizi e Attrezzature - Geneva Residence -","isPartOf":{"@id":"https:\/\/www.geneva-residence.fr\/it\/#website"},"datePublished":"2024-12-16T22:09:05+00:00","dateModified":"2025-07-10T15:10:56+00:00","description":"Geneva R\u00e9sidence mette a disposizione 71 sistemazioni completamente attrezzate per farti sentire come a casa. Ogni studio e appartamento include una cucina funzionale con microonde, frigorifero e bollitore, oltre alla TV satellitare e l'accesso Wi-Fi. \u00c8 possibile prenotare un parcheggio (9\u20ac\/notte, altezza massima 1,90 m) e un solo animale domestico (solo cane o gatto, 5\u20ac\/notte) all'arrivo, in base alla disponibilit\u00e0. &nbsp;.","breadcrumb":{"@id":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.geneva-residence.fr\/it\/servizi-e-attrezzature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.geneva-residence.fr\/it\/"},{"@type":"ListItem","position":2,"name":"Servizi e Attrezzature"}]},{"@type":"WebSite","@id":"https:\/\/www.geneva-residence.fr\/it\/#website","url":"https:\/\/www.geneva-residence.fr\/it\/","name":"Geneva Residence","description":"","publisher":{"@id":"https:\/\/www.geneva-residence.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geneva-residence.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.geneva-residence.fr\/it\/#organization","name":"Geneva Residence","url":"https:\/\/www.geneva-residence.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geneva-residence.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/geneva-residence-paprika.ms2.decms.eu\/wp-content\/uploads\/sites\/183\/2024\/12\/Logo-pour-en-tete-1.png","contentUrl":"https:\/\/geneva-residence-paprika.ms2.decms.eu\/wp-content\/uploads\/sites\/183\/2024\/12\/Logo-pour-en-tete-1.png","width":2200,"height":795,"caption":"Geneva Residence"},"image":{"@id":"https:\/\/www.geneva-residence.fr\/it\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/pages\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/users\/192"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":0,"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/pages\/194\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geneva-residence.fr\/it\/wp-json\/wp\/v2\/media?parent=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}